{"id":53,"count":1,"description":"","link":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/category\/neues-vom-verwaltungsrat\/","name":"Neues vom Verwaltungsrat","slug":"neues-vom-verwaltungsrat","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neues vom Verwaltungsrat Archive - September 2022<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neues vom Verwaltungsrat Archive - September 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/category\/neues-vom-verwaltungsrat\/\" \/>\n<meta property=\"og:site_name\" content=\"September 2022\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/category\\\/neues-vom-verwaltungsrat\\\/\",\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/category\\\/neues-vom-verwaltungsrat\\\/\",\"name\":\"Neues vom Verwaltungsrat Archive - September 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/category\\\/neues-vom-verwaltungsrat\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/category\\\/neues-vom-verwaltungsrat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neues vom Verwaltungsrat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#website\",\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/\",\"name\":\"September 2022\",\"description\":\"Eine weitere IKK Magazin Ausgaben Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neues vom Verwaltungsrat Archive - September 2022","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Neues vom Verwaltungsrat Archive - September 2022","og_url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/category\/neues-vom-verwaltungsrat\/","og_site_name":"September 2022","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/category\/neues-vom-verwaltungsrat\/","url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/category\/neues-vom-verwaltungsrat\/","name":"Neues vom Verwaltungsrat Archive - September 2022","isPartOf":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#website"},"breadcrumb":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/category\/neues-vom-verwaltungsrat\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/category\/neues-vom-verwaltungsrat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/"},{"@type":"ListItem","position":2,"name":"Neues vom Verwaltungsrat"}]},{"@type":"WebSite","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#website","url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/","name":"September 2022","description":"Eine weitere IKK Magazin Ausgaben Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/categories\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/posts?categories=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}