{"id":4026,"date":"2022-08-01T00:11:15","date_gmt":"2022-07-31T22:11:15","guid":{"rendered":"https:\/\/magazin.ikk-suedwest.de\/august-2021\/?p=4026"},"modified":"2022-09-08T10:28:11","modified_gmt":"2022-09-08T08:28:11","slug":"fur-ein-aktives-leben","status":"publish","type":"post","link":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/","title":{"rendered":"F\u00fcr ein aktives Leben"},"content":{"rendered":"<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-ein-aktives-leben%2F&text=F%C3%BCr%20ein%20aktives%20Leben\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-ein-aktives-leben%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-ein-aktives-leben%2F%20F%C3%BCr%20ein%20aktives%20Leben\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"mailto:?body=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-ein-aktives-leben%2F&subject=F%C3%BCr%20ein%20aktives%20Leben\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"block-7aff71a3-c9fd-4bde-b12c-446c8d1dfcb2\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv-1024x684.jpg\" alt=\"\" class=\"wp-image-5478\" srcset=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv-1024x684.jpg 1024w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv-300x200.jpg 300w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv-768x513.jpg 768w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv-370x247.jpg 370w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv-270x180.jpg 270w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv-570x381.jpg 570w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv-749x500.jpg 749w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv-740x494.jpg 740w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv.jpg 1225w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"has-text-color wp-block-heading\" id=\"mit-ihrer-ikk-aktiv-im-neuen-jahr\" style=\"color:#009fe3\">F\u00fcr ein aktives Leben<\/h1>\n\n\n\n<p class=\"has-text-color has-large-font-size wp-block-paragraph\" style=\"color:#009fe3\">Mit den Kindern im Garten toben. Mit dem E-Bike die Region erkunden. In aller Ruhe durch die Natur wandern. All das geht dann am besten, wenn man fit und gesund ist. Damit das m\u00f6glichst lange so bleibt, haben wir mit IKK Lifeaktiv genau das Richtige f\u00fcr Sie.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/02\/ikk_logo_lifeaktiv_2111_rgb_zw_rz-1.svg\" alt=\"\" class=\"wp-image-4907\" width=\"300\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ausreichend bewegen, gesund ern\u00e4hren und auch noch Zeit zum Entspannen finden \u2013 gar nicht so einfach im hektischen Alltag. Damit Sie den \u00dcberblick behalten und ein Leben lang aktiv bleiben k\u00f6nnen, gibt es IKK Lifeaktiv. Auf unserer Webseite finden Sie genau die Angebote, die zu Ihnen passen \u2013 mit wenigen Klicks geht\u2019s zu Kursen, Gesundheitsreisen, Seminaren und Coachings.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" id=\"vorfreude\" style=\"color:#009fe3\"><img decoding=\"async\" class=\"wp-image-3714\" style=\"width: 60px; margin-right: 20px\" src=\"\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/IKK_Icon_Lifeaktiv_Praevention_bewegt_RZ.svg\" alt=\"\">Wer rastet, der rostet<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Seit einigen Jahren zeigt sich immer deutlicher, dass wir uns zu wenig bewegen. Kein Wunder: In B\u00fcrojobs verbringen wir acht Stunden und mehr vor dem Bildschirm, zu Hause wartet nach einem anstrengenden Tag die bequeme Couch auf uns. Darum gilt Sitzen mit seinen negativen Effekten inzwischen als das neue Rauchen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Den inneren Schweinehund zu \u00fcberwinden, ist nicht einfach. Wir helfen Ihnen, ihm die Stirn zu bieten: Wie w\u00e4re es beispielsweise mit unseren Seminaren rund um Ausdauertraining? Oder mit einem Trainingsprogramm rund um R\u00fcckengesundheit? Mehr Bewegung war noch nie so einfach.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" id=\"vorfreude\" style=\"color:#009fe3\"><img decoding=\"async\" class=\"wp-image-3714\" style=\"width: 60px; margin-right: 20px\" src=\"\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/IKK_Icon_Lifeaktiv_Praevention_schmeckt_RZ.svg\" alt=\"\">Du bist, was du isst<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">T\u00fctensuppen, Fertiggerichte, Fast Food \u2013 wenn es darum geht, schnell etwas zu essen zuzubereiten oder zu kaufen, sind industriell verarbeitete Lebensmittel nicht weit. Allerdings sind sie mit ihren Konservierungsmitteln und hohen Anteilen an Fetten und Zucker in den seltensten F\u00e4llen gesund.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dabei muss gute Ern\u00e4hrung gar nicht schwer sein. Das beweisen beispielsweise unsere Seminare und Vortr\u00e4ge rund um Kohlenhydrate oder Proteine. Und f\u00fcr Menschen, die erkrankt sind, bieten wir medizinische Ern\u00e4hrungstherapien an \u2013 oft k\u00f6nnen mit einfachen Ern\u00e4hrungsumstellungen bereits Erfolge erzielt werden.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" id=\"vorfreude\" style=\"color:#009fe3\"><img decoding=\"async\" class=\"wp-image-3714\" style=\"width: 60px; margin-right: 20px\" src=\"\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/IKK_Icon_Lifeaktiv_Praevention_entspannt_RZ.svg\" alt=\"\">In der Ruhe liegt die Kraft<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Hektik und Stress sind heute allgegenw\u00e4rtig, Beruf und Familie unter einen Hut zu bringen, verlangt uns einiges ab. Umso wichtiger ist es, sich hin und wieder Auszeiten zu g\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie w\u00e4re es beispielsweise mit einer Gesundheitsreise in ein Wellness-Hotel, wo Sie es sich richtig gutgehen lassen k\u00f6nnen? Oder tun Sie in unseren Yoga- oder Tai-Chi-Kursen etwas f\u00fcr K\u00f6rper, Geist und Seele \u2013 mit unseren Online-Angeboten sogar im eigenen Wohnzimmer.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" id=\"vorfreude\" style=\"color:#009fe3\"><img decoding=\"async\" class=\"wp-image-3714\" style=\"width: 60px; margin-right: 20px\" src=\"\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/IKK_Icon_Lifeaktiv_Praevention_befreit_RZ.svg\" alt=\"\">S\u00fcchten den Kampf ansagen<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mit Gewohnheiten zu brechen, ist alles andere als leicht. Raucher beispielsweise kennen das aus leidvoller Erfahrung: Der Entschluss aufzuh\u00f6ren ist gefasst, trotzdem f\u00e4llt es schwer, auf die geliebte Zigarette zu verzichten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei S\u00fcchten und Abh\u00e4ngigkeiten ist das keine Seltenheit. Aber auch hier gibt es L\u00f6sungen \u2013 und wir unterst\u00fctzen Sie dabei, sie umzusetzen. In Seminaren und Beratungen, etwa \u00fcber unsere Coaching-Hotline, lernen Sie unter anderem, Verhaltensmuster zu erkennen und ihnen entgegenzuwirken. So wird es m\u00f6glich, bald wieder ein selbstbestimmtes Leben zu f\u00fchren.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-gridlove-acc-color has-text-color has-large-font-size wp-block-paragraph\" style=\"margin-bottom: 5px\"><strong>Das alles \u2013 und noch viel mehr<\/strong><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Diese und viele weitere Angebote h\u00e4lt IKK Lifeaktiv f\u00fcr Sie bereit. Aber nicht nur das: Auch Kitas, Schulen, Kommunen und Selbsthilfegruppen finden hier genau das Richtige. Von Kursen f\u00fcr Erzieher oder Lehrer bis hin zu Unterst\u00fctzungsangeboten f\u00fcr Selbsthilfe-Organisationen&nbsp;\u2013 schauen Sie einfach auf unserer Webseite vorbei.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#009fe3\"> <meta charset=\"utf-8\"><a href=\"https:\/\/lifeaktiv.ikk-suedwest.de\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" id=\"a2323\" class=\"wp-image-2769\" src=\"https:\/\/magazin.ikk-suedwest.de\/august-2021\/wp-content\/uploads\/sites\/6\/2021\/08\/noun_External-Link_4147197.svg\" alt=\"\" width=\"28\" height=\"35\"><strong>Mehr zu <\/strong><em>IKK Lifeaktiv<\/em><\/a><\/p>\n\n\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-ein-aktives-leben%2F&text=F%C3%BCr%20ein%20aktives%20Leben\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-ein-aktives-leben%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-ein-aktives-leben%2F%20F%C3%BCr%20ein%20aktives%20Leben\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"mailto:?body=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-ein-aktives-leben%2F&subject=F%C3%BCr%20ein%20aktives%20Leben\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-39697d9b wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"javascript:history.back()\" style=\"background-color:#009de9\">Zur\u00fcck<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit den Kindern im Garten toben. Mit dem E-Bike die Region erkunden. In aller Ruhe durch die Natur wandern &#8230;<\/p>\n","protected":false},"author":1,"featured_media":5478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","favoriteCount":8,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-4026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-service"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00fcr ein aktives Leben - September 2022<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fcr ein aktives Leben - September 2022\" \/>\n<meta property=\"og:description\" content=\"Mit den Kindern im Garten toben. Mit dem E-Bike die Region erkunden. In aller Ruhe durch die Natur wandern ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/\" \/>\n<meta property=\"og:site_name\" content=\"September 2022\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-31T22:11:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-08T08:28:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1225\" \/>\n\t<meta property=\"og:image:height\" content=\"818\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fbo_master\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"fbo_master\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/\"},\"author\":{\"name\":\"fbo_master\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#\\\/schema\\\/person\\\/636237f711a5aed151e44ddcc2de114a\"},\"headline\":\"F\u00fcr ein aktives Leben\",\"datePublished\":\"2022-07-31T22:11:15+00:00\",\"dateModified\":\"2022-09-08T08:28:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/\"},\"wordCount\":547,\"image\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/08\\\/ikk_fm_2202_s20_lifeaktiv.jpg\",\"articleSection\":[\"Service\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/\",\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/\",\"name\":\"F\u00fcr ein aktives Leben - September 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/08\\\/ikk_fm_2202_s20_lifeaktiv.jpg\",\"datePublished\":\"2022-07-31T22:11:15+00:00\",\"dateModified\":\"2022-09-08T08:28:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#\\\/schema\\\/person\\\/636237f711a5aed151e44ddcc2de114a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/08\\\/ikk_fm_2202_s20_lifeaktiv.jpg\",\"contentUrl\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/08\\\/ikk_fm_2202_s20_lifeaktiv.jpg\",\"width\":1225,\"height\":818},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-ein-aktives-leben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00fcr ein aktives Leben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#website\",\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/\",\"name\":\"September 2022\",\"description\":\"Eine weitere IKK Magazin Ausgaben Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#\\\/schema\\\/person\\\/636237f711a5aed151e44ddcc2de114a\",\"name\":\"fbo_master\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g\",\"caption\":\"fbo_master\"},\"sameAs\":[\"https:\\\/\\\/magazin.ikk-suedwest.de\"],\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/author\\\/fbo_master\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00fcr ein aktives Leben - September 2022","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"F\u00fcr ein aktives Leben - September 2022","og_description":"Mit den Kindern im Garten toben. Mit dem E-Bike die Region erkunden. In aller Ruhe durch die Natur wandern ...","og_url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/","og_site_name":"September 2022","article_published_time":"2022-07-31T22:11:15+00:00","article_modified_time":"2022-09-08T08:28:11+00:00","og_image":[{"width":1225,"height":818,"url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv.jpg","type":"image\/jpeg"}],"author":"fbo_master","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"fbo_master","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/#article","isPartOf":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/"},"author":{"name":"fbo_master","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#\/schema\/person\/636237f711a5aed151e44ddcc2de114a"},"headline":"F\u00fcr ein aktives Leben","datePublished":"2022-07-31T22:11:15+00:00","dateModified":"2022-09-08T08:28:11+00:00","mainEntityOfPage":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/"},"wordCount":547,"image":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/#primaryimage"},"thumbnailUrl":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv.jpg","articleSection":["Service"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/","url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/","name":"F\u00fcr ein aktives Leben - September 2022","isPartOf":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/#primaryimage"},"image":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/#primaryimage"},"thumbnailUrl":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv.jpg","datePublished":"2022-07-31T22:11:15+00:00","dateModified":"2022-09-08T08:28:11+00:00","author":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#\/schema\/person\/636237f711a5aed151e44ddcc2de114a"},"breadcrumb":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/#primaryimage","url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv.jpg","contentUrl":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2021\/08\/ikk_fm_2202_s20_lifeaktiv.jpg","width":1225,"height":818},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-ein-aktives-leben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/"},{"@type":"ListItem","position":2,"name":"F\u00fcr ein aktives Leben"}]},{"@type":"WebSite","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#website","url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/","name":"September 2022","description":"Eine weitere IKK Magazin Ausgaben Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#\/schema\/person\/636237f711a5aed151e44ddcc2de114a","name":"fbo_master","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g","caption":"fbo_master"},"sameAs":["https:\/\/magazin.ikk-suedwest.de"],"url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/author\/fbo_master\/"}]}},"_links":{"self":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/posts\/4026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/comments?post=4026"}],"version-history":[{"count":10,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/posts\/4026\/revisions"}],"predecessor-version":[{"id":5886,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/posts\/4026\/revisions\/5886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/media\/5478"}],"wp:attachment":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/media?parent=4026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/categories?post=4026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/tags?post=4026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}