{"id":5520,"date":"2022-08-01T00:08:45","date_gmt":"2022-07-31T22:08:45","guid":{"rendered":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/?p=5520"},"modified":"2022-09-08T10:27:10","modified_gmt":"2022-09-08T08:27:10","slug":"fur-kinder-da-sein","status":"publish","type":"post","link":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/","title":{"rendered":"F\u00fcr Kinder da sein"},"content":{"rendered":"<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-kinder-da-sein%2F&text=F%C3%BCr%20Kinder%20da%20sein\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-kinder-da-sein%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-kinder-da-sein%2F%20F%C3%BCr%20Kinder%20da%20sein\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"mailto:?body=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-kinder-da-sein%2F&subject=F%C3%BCr%20Kinder%20da%20sein\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large ticss-6ab86279\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet-1024x684.jpg\" alt=\"\" class=\"wp-image-5521\" srcset=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet-1024x684.jpg 1024w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet-300x200.jpg 300w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet-768x513.jpg 768w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet-370x247.jpg 370w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet-270x180.jpg 270w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet-570x381.jpg 570w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet-749x500.jpg 749w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet-740x494.jpg 740w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet.jpg 1225w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"ticss-c7eb346c has-text-color wp-block-heading\" id=\"digitale-gesundheit-mit-modernen-tools-sicher-in-die-zukunft\" style=\"color:#009fe3\">F\u00fcr Kinder da sein<\/h1>\n\n\n\n<p class=\"has-text-color has-large-font-size wp-block-paragraph\" style=\"color:#009fe3\">Psychische Erkrankungen sind f\u00fcr viele immer noch ein Tabuthema, \u00fcber das nur selten offen gesprochen wird. Besonders schwierig ist es f\u00fcr Kinder, deren Eltern psychisch erkrankt sind. Ihnen fehlt je nach Alter nicht nur das Verst\u00e4ndnis daf\u00fcr, was ihre Eltern durchmachen, sondern auch die M\u00f6glichkeit, damit umzugehen. Mit CHIMPS-NET bieten wir betroffenen Familien Hilfe an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gerade weil psychische Erkrankungen nicht sichtbar sind, vergisst man leicht, wie h\u00e4ufig sie wirklich sind: Laut dem Bundesfamilienministerium wachsen drei bis vier Millionen Kinder in Familien auf, in denen mindestens ein Elternteil psychisch erkrankt ist. Durch die besondere Situation ist es in diesen Familien oftmals so, dass sich Heranwachsende ihre eigenen Sorgen und \u00c4ngste nicht anmerken lassen. Trotzdem leiden sie \u2013 und haben ein deutlich h\u00f6heres Risiko, selbst eine psychische Erkrankung zu entwickeln.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das wollen wir unbedingt vermeiden \u2013 darum sind wir nun Teil von CHIMPS-NET, einem Projekt, das betroffene Kinder und Jugendliche unterst\u00fctzt. Die Hilfsangebote, die je nach famili\u00e4rer Situation von kurzen Pr\u00e4ventionsma\u00dfnahmen \u00fcber Mischformen aus Pr\u00e4vention und Therapie bis hin zu familienorientierter Therapie mit Psychotherapeuten reichen, er\u00f6ffnen viele M\u00f6glichkeiten, die Gesundheit zu sch\u00fctzen oder zu verbessern.<\/p>\n\n\n\n<p class=\"has-text-color has-large-font-size wp-block-paragraph\" style=\"color:#009fe3\">Wie funktioniert die Teilnahme?<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"210\" src=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_beitragsbild_s13_chimpsnet.png\" alt=\"\" class=\"wp-image-5606\" srcset=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_beitragsbild_s13_chimpsnet.png 275w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_beitragsbild_s13_chimpsnet-270x206.png 270w, https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_beitragsbild_s13_chimpsnet-80x60.png 80w\" sizes=\"auto, (max-width: 275px) 100vw, 275px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Wer sich f\u00fcr CHIMPS-NET anmelden m\u00f6chte, kann das ganz leicht tun: Einfach eine der teilnehmenden Kliniken kontaktieren. In Hessen, Rheinland-Pfalz und dem Saarland gibt es vier Zentren, die mit CHIMPS-NET zusammenarbeiten: das Universit\u00e4tsklinikum Gie\u00dfen und Marburg, das Universit\u00e4tsklinikum Frankfurt, die Universit\u00e4t Ko\u00adblenz-Landau und das Universit\u00e4tsklinikum des Saarlandes in Homburg. Die Kontaktseite haben wir unter dem Artikel f\u00fcr Sie verlinkt. Voraussetzung ist, dass mindestens ein Elternteil psychisch erkrankt ist und die Kinder zwischen 3 und 18 Jahren alt sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-gridlove-acc-color has-text-color wp-block-paragraph\"><strong><meta charset=\"utf-8\"><\/strong><\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#009fe3\"> <meta charset=\"utf-8\"><a href=\"https:\/\/www.ikk-suedwest.de\/leistungen\/versorgung-fuer-kinder-psychisch-kranker-eltern-chimps-net\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" id=\"a2323\" class=\"wp-image-2769\" src=\"https:\/\/magazin.ikk-suedwest.de\/august-2021\/wp-content\/uploads\/sites\/6\/2021\/08\/noun_External-Link_4147197.svg\" alt=\"\" width=\"28\" height=\"35\"><strong>Mehr zu <\/strong><em>CHIMPS-NET<\/em><\/a><\/p>\n\n\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-kinder-da-sein%2F&text=F%C3%BCr%20Kinder%20da%20sein\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-kinder-da-sein%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-kinder-da-sein%2F%20F%C3%BCr%20Kinder%20da%20sein\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"mailto:?body=https%3A%2F%2Fmagazin.ikk-suedwest.de%2Fseptember-2022%2Ffur-kinder-da-sein%2F&subject=F%C3%BCr%20Kinder%20da%20sein\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-39697d9b wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"javascript:history.back()\" style=\"background-color:#009fe3\">Zur\u00fcck<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wenn Pflegebed\u00fcrftigkeit eintritt, stehen Betroffene und Angeh\u00f6rige vor einer gro\u00dfen Herausforderung &#8230;<\/p>\n","protected":false},"author":1,"featured_media":5521,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","favoriteCount":4,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-5520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-service"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00fcr Kinder da sein - September 2022<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fcr Kinder da sein - September 2022\" \/>\n<meta property=\"og:description\" content=\"Wenn Pflegebed\u00fcrftigkeit eintritt, stehen Betroffene und Angeh\u00f6rige vor einer gro\u00dfen Herausforderung ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/\" \/>\n<meta property=\"og:site_name\" content=\"September 2022\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-31T22:08:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-08T08:27:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1225\" \/>\n\t<meta property=\"og:image:height\" content=\"818\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fbo_master\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"fbo_master\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/\"},\"author\":{\"name\":\"fbo_master\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#\\\/schema\\\/person\\\/636237f711a5aed151e44ddcc2de114a\"},\"headline\":\"F\u00fcr Kinder da sein\",\"datePublished\":\"2022-07-31T22:08:45+00:00\",\"dateModified\":\"2022-09-08T08:27:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/\"},\"wordCount\":302,\"image\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/08\\\/ikk_fm_2202_s13_chimpsnet.jpg\",\"articleSection\":[\"Service\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/\",\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/\",\"name\":\"F\u00fcr Kinder da sein - September 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/08\\\/ikk_fm_2202_s13_chimpsnet.jpg\",\"datePublished\":\"2022-07-31T22:08:45+00:00\",\"dateModified\":\"2022-09-08T08:27:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#\\\/schema\\\/person\\\/636237f711a5aed151e44ddcc2de114a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/08\\\/ikk_fm_2202_s13_chimpsnet.jpg\",\"contentUrl\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/08\\\/ikk_fm_2202_s13_chimpsnet.jpg\",\"width\":1225,\"height\":818},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/fur-kinder-da-sein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00fcr Kinder da sein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#website\",\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/\",\"name\":\"September 2022\",\"description\":\"Eine weitere IKK Magazin Ausgaben Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/#\\\/schema\\\/person\\\/636237f711a5aed151e44ddcc2de114a\",\"name\":\"fbo_master\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g\",\"caption\":\"fbo_master\"},\"sameAs\":[\"https:\\\/\\\/magazin.ikk-suedwest.de\"],\"url\":\"https:\\\/\\\/magazin.ikk-suedwest.de\\\/september-2022\\\/author\\\/fbo_master\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00fcr Kinder da sein - September 2022","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"F\u00fcr Kinder da sein - September 2022","og_description":"Wenn Pflegebed\u00fcrftigkeit eintritt, stehen Betroffene und Angeh\u00f6rige vor einer gro\u00dfen Herausforderung ...","og_url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/","og_site_name":"September 2022","article_published_time":"2022-07-31T22:08:45+00:00","article_modified_time":"2022-09-08T08:27:10+00:00","og_image":[{"width":1225,"height":818,"url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet.jpg","type":"image\/jpeg"}],"author":"fbo_master","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"fbo_master","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/#article","isPartOf":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/"},"author":{"name":"fbo_master","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#\/schema\/person\/636237f711a5aed151e44ddcc2de114a"},"headline":"F\u00fcr Kinder da sein","datePublished":"2022-07-31T22:08:45+00:00","dateModified":"2022-09-08T08:27:10+00:00","mainEntityOfPage":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/"},"wordCount":302,"image":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet.jpg","articleSection":["Service"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/","url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/","name":"F\u00fcr Kinder da sein - September 2022","isPartOf":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/#primaryimage"},"image":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet.jpg","datePublished":"2022-07-31T22:08:45+00:00","dateModified":"2022-09-08T08:27:10+00:00","author":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#\/schema\/person\/636237f711a5aed151e44ddcc2de114a"},"breadcrumb":{"@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/#primaryimage","url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet.jpg","contentUrl":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-content\/uploads\/sites\/7\/2022\/08\/ikk_fm_2202_s13_chimpsnet.jpg","width":1225,"height":818},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/fur-kinder-da-sein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/"},{"@type":"ListItem","position":2,"name":"F\u00fcr Kinder da sein"}]},{"@type":"WebSite","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#website","url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/","name":"September 2022","description":"Eine weitere IKK Magazin Ausgaben Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/#\/schema\/person\/636237f711a5aed151e44ddcc2de114a","name":"fbo_master","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e042e587c1d6c68d3fadd024e871a65399da22a9ef5e23b274af331bde574af?s=96&d=mm&r=g","caption":"fbo_master"},"sameAs":["https:\/\/magazin.ikk-suedwest.de"],"url":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/author\/fbo_master\/"}]}},"_links":{"self":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/posts\/5520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/comments?post=5520"}],"version-history":[{"count":9,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/posts\/5520\/revisions"}],"predecessor-version":[{"id":5885,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/posts\/5520\/revisions\/5885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/media\/5521"}],"wp:attachment":[{"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/media?parent=5520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/categories?post=5520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magazin.ikk-suedwest.de\/september-2022\/wp-json\/wp\/v2\/tags?post=5520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}